{"id":109429,"date":"2023-03-01T11:51:22","date_gmt":"2023-03-01T11:51:22","guid":{"rendered":"https:\/\/worldofeurope.com\/shop\/unkategorisiert\/pukka-tea-elderberry-echinacea-20-tea-bags-pukka-tea-bags-tea-pukka-14-ounce-total\/"},"modified":"2025-11-17T15:06:35","modified_gmt":"2025-11-17T15:06:35","slug":"pukka-tea-elderberry-echinacea-20-tea-bags-pukka-tea-bags-tea-pukka-14-ounce-total","status":"publish","type":"product","link":"https:\/\/worldofeurope.com\/de\/shop\/tee\/pukka-tea-elderberry-echinacea-20-tea-bags-pukka-tea-bags-tea-pukka-14-ounce-total\/","title":{"rendered":"Pukka Tea | Holunder &#038; Echinacea 20 Teebeutel | Pukka Teebeutel | Tee Pukka | 1,4 Unzen insgesamt"},"content":{"rendered":"<p>Pukka Tea ist eine Marke f\u00fcr Kr\u00e4uter- und Fr\u00fcchtetees aus biologischen Zutaten. Es handelt sich um eine einzigartige Mischung aus Kr\u00e4utern, Gew\u00fcrzen und Fr\u00fcchten, die sorgf\u00e4ltig ausgew\u00e4hlt wurden, um einen k\u00f6stlichen und erfrischenden Tee zu kreieren. Der Tee von Pukka wird aus ethisch einwandfreien Zutaten hergestellt und ist frei von k\u00fcnstlichen Aromen, Farbstoffen und Konservierungsstoffen. Die Pukka-Teebeutel sind einzeln verpackt, um Frische zu gew\u00e4hrleisten, und in verschiedenen Geschmacksrichtungen erh\u00e4ltlich. Pukka Tea ist eine gute Wahl f\u00fcr alle, die einen k\u00f6stlichen und gesunden Tee ohne k\u00fcnstliche Inhaltsstoffe suchen. Bestellen Sie jetzt 20 Teebeutel Holunder &#038; Echinacea! <\/p>\n<p><span style=\"font-weight: 400;\">Pukka-Tee  aus Belgien <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pukka-Teebeutel  \u2013 genie\u00dfen Sie sie mit Familie oder Freunden <\/span><\/p>\n<p><span style=\"font-weight: 400;\"> 1,4 Unzen insgesamt | 40 Gramm insgesamt <\/span><\/p>\n<p><span style=\"font-weight: 400;\"> G\u00f6nnen Sie sich etwas. Achten Sie darauf, dass Ihnen der Vorrat nicht ausgeht <\/span><\/p>\n<p><span style=\"font-weight: 400;\"> Bestellen Sie jetzt Pukka-Tee! <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pukka Tea ist eine Marke f\u00fcr Kr\u00e4uter- und Fr\u00fcchtetees aus biologischen Zutaten. Es handelt sich um eine einzigartige Mischung aus Kr\u00e4utern, Gew\u00fcrzen und Fr\u00fcchten, die sorgf\u00e4ltig ausgew\u00e4hlt wurden, um einen k\u00f6stlichen und erfrischenden Tee zu kreieren. Der Tee von Pukka wird aus ethisch einwandfreien Zutaten hergestellt und ist frei von k\u00fcnstlichen Aromen, Farbstoffen und Konservierungsstoffen. Die Pukka-Teebeutel sind einzeln verpackt, um Frische zu gew\u00e4hrleisten, und in verschiedenen Geschmacksrichtungen erh\u00e4ltlich. Pukka Tea ist eine gute Wahl f\u00fcr alle, die einen k\u00f6stlichen und gesunden Tee ohne k\u00fcnstliche Inhaltsstoffe suchen.  Bestellen Sie jetzt 20 Teebeutel Elderberry &#038; Echinacea!<\/p>\n","protected":false},"featured_media":109430,"template":"","meta":[],"product_brand":[],"product_cat":[79715],"product_tag":[79683],"class_list":["post-109429","product","type-product","status-publish","has-post-thumbnail","product_cat-tee","product_tag-belgien","pa_bullet-point-1-pukka-tea-from-belgium-de","pa_bullet-point-1-de-pukka-tee-aus-belgien-de","pa_bullet-point-1-esp-pukka-tea-desde-belgica-de","pa_bullet-point-1-fr-pukka-tea-belgique-de","pa_bullet-point-1-it-te-pukka-dal-belgio-de","pa_bullet-point-2-pukka-tea-bags-enjoy-with-family-or-friends-de","pa_bullet-point-2-de-tee-italien-zum-geniessen-mit-der-familie-oder-mit-freunden-de","pa_bullet-point-2-esp-puka-te-para-disfrutar-con-la-familia-o-los-amigos-de","pa_bullet-point-2-fr-pukka-infusion-a-savourer-en-famille-ou-entre-amis-de","pa_bullet-point-2-it-pukka-tea-per-godere-con-la-famiglia-o-gli-amici-de","pa_bullet-point-3-1-de","pa_bullet-point-3-4-ounce-total-40-gramtotal-de","pa_bullet-point-3-de-40-gram-total-de","pa_bullet-point-3-esp-40-gramo-total-de","pa_bullet-point-3-fr-40-gramme-total-de","pa_bullet-point-3-it-40-grammo-total-de","pa_bullet-point-4-indulge-yourself-be-sure-not-to-run-out-of-stock-de","pa_bullet-point-4-de-dass-ihnen-nicht-der-vorrat-ausgeht-de","pa_bullet-point-4-de-stellen-sie-sicher-de","pa_bullet-point-4-esp-asegurese-de-no-quedarse-sin-existencias-de","pa_bullet-point-4-fr-veillez-a-ne-pas-etre-en-rupture-de-stock-de","pa_bullet-point-4-it-assicurati-di-non-esaurire-le-scorte-de","pa_bullet-point-5-order-tea-pukka-now-de","pa_bullet-point-5-de-bestellen-sie-pukka-ingwer-jetzt-de","pa_bullet-point-5-esp-comprar-pukka-infusiones-ahora-de","pa_bullet-point-5-fr-acheter-pukka-the-maintenant-de","pa_bullet-point-5-it-compra-puka-te-ora-de","pa_title-de-pukka-tee-holunder-echinacea-20-teebeutel-tee-italien-pukka-ingwer-40-gramm-total-de","pa_title-esp-pukka-tea-sauco-y-equinacea-20-bolsitas-de-te-puka-te-pukka-infusiones-40-gramo-total-de","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/worldofeurope.com\/de\/wp-json\/wp\/v2\/product\/109429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/worldofeurope.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/worldofeurope.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/worldofeurope.com\/de\/wp-json\/wp\/v2\/media\/109430"}],"wp:attachment":[{"href":"https:\/\/worldofeurope.com\/de\/wp-json\/wp\/v2\/media?parent=109429"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/worldofeurope.com\/de\/wp-json\/wp\/v2\/product_brand?post=109429"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/worldofeurope.com\/de\/wp-json\/wp\/v2\/product_cat?post=109429"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/worldofeurope.com\/de\/wp-json\/wp\/v2\/product_tag?post=109429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}