{"id":127251,"date":"2023-03-01T12:16:17","date_gmt":"2023-03-01T12:16:17","guid":{"rendered":"https:\/\/worldofeurope.com\/shop\/non%20class\u00e9\/devos-lemmens-sauce-mayonnaise-with-lemon-300-ml-devos-lemmens-belgian-sauce-105-ounce-total\/"},"modified":"2026-06-27T21:16:08","modified_gmt":"2026-06-27T21:16:08","slug":"devos-lemmens-sauce-mayonnaise-with-lemon-300-ml-devos-lemmens-belgian-sauce-105-ounce-total","status":"publish","type":"product","link":"https:\/\/worldofeurope.com\/fr\/shop\/non-classe\/devos-lemmens-sauce-mayonnaise-with-lemon-300-ml-devos-lemmens-belgian-sauce-105-ounce-total\/","title":{"rendered":"Sauce Devos Lemmens | Mayonnaise au citron 300 ml | Devos Lemmens | Sauce belge | 10,5 oz au total"},"content":{"rendered":"<p>La sauce Devos Lemmens est une sauce belge qui existe depuis le d\u00e9but des ann\u00e9es 1900. C&rsquo;est un m\u00e9lange unique d&rsquo;\u00e9pices, d&rsquo;herbes et de l\u00e9gumes qui lui conf\u00e8re une saveur unique. Elle accompagne \u00e0 merveille tous les plats et peut \u00eatre utilis\u00e9e comme marinade, trempette ou m\u00eame comme condiment. C&rsquo;est un excellent moyen d&rsquo;ajouter de la saveur \u00e0 n&rsquo;importe quel plat, et c&rsquo;est l&rsquo;une des sauces pr\u00e9f\u00e9r\u00e9es des fans de Devos Lemmens. La sauce est compos\u00e9e d&rsquo;ingr\u00e9dients enti\u00e8rement naturels et ne contient ni conservateurs ni ar\u00f4mes artificiels. Elle est id\u00e9ale pour ajouter une touche suppl\u00e9mentaire \u00e0 tous vos plats et plaira \u00e0 coup s\u00fbr \u00e0 tous vos convives. Commandez d\u00e8s maintenant la mayonnaise au citron 300 ml ! <\/p>\n<p><span style=\"font-weight: 400;\">Sauce Devos Lemmens  de Belgique <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Devos Lemmens  &#8211; \u00e0 d\u00e9guster en famille ou entre amis <\/span><\/p>\n<p><span style=\"font-weight: 400;\"> 10,5 onces au total | 300 grammes au total <\/span><\/p>\n<p><span style=\"font-weight: 400;\"> Faites-vous plaisir. Ne manquez pas cette occasion <\/span><\/p>\n<p><span style=\"font-weight: 400;\"> Commandez d\u00e8s maintenant la sauce belge ! <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sauce Devos Lemmens est une sauce belge qui existe depuis le d\u00e9but des ann\u00e9es 1900. C&rsquo;est un m\u00e9lange unique d&rsquo;\u00e9pices, d&rsquo;herbes et de l\u00e9gumes qui lui conf\u00e8re une saveur unique. Elle accompagne \u00e0 merveille tous les plats et peut \u00eatre utilis\u00e9e comme marinade, trempette ou m\u00eame comme condiment. C&rsquo;est un excellent moyen d&rsquo;ajouter de la saveur \u00e0 tous vos plats, et c&rsquo;est l&rsquo;un des produits pr\u00e9f\u00e9r\u00e9s des fans de Devos Lemmens. La sauce est compos\u00e9e d&rsquo;ingr\u00e9dients enti\u00e8rement naturels et ne contient ni conservateurs ni ar\u00f4mes artificiels. Elle est id\u00e9ale pour ajouter une touche suppl\u00e9mentaire \u00e0 tous vos plats et plaira \u00e0 coup s\u00fbr \u00e0 tous vos convives. Commandez d\u00e8s maintenant la mayonnaise au citron 300 ml !<\/p>\n","protected":false},"featured_media":127252,"template":"","meta":[],"product_brand":[],"product_cat":[79731],"product_tag":[79736],"class_list":{"0":"post-127251","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-non-classe","7":"product_tag-belgique","8":"pa_bullet-point-1-devos-lemmens-sauce-from-belgium-fr","9":"pa_bullet-point-1-de-devos-lemmens-saucen-aus-belgien-fr","10":"pa_bullet-point-1-esp-devos-lemmens-salsas-desde-belgica-fr","11":"pa_bullet-point-1-fr-devos-lemmens-belgique-fr","12":"pa_bullet-point-1-it-devos-lemmens-dal-belgio-fr","13":"pa_bullet-point-2-devos-lemmens-enjoy-with-family-or-friends-fr","14":"pa_bullet-point-2-de-belgische-saucen-zum-geniessen-mit-der-familie-oder-mit-freunden-fr","15":"pa_bullet-point-2-esp-salsas-belgas-para-disfrutar-con-la-familia-o-los-amigos-fr","16":"pa_bullet-point-2-fr-sauce-devos-lemmens-a-savourer-en-famille-ou-entre-amis-fr","17":"pa_bullet-point-2-it-salsa-belgio-per-godere-con-la-famiglia-o-gli-amici-fr","18":"pa_bullet-point-3-10-fr","19":"pa_bullet-point-3-5-ounce-total-300-gramtotal-fr","20":"pa_bullet-point-3-de-300-gram-total-fr","21":"pa_bullet-point-3-esp-300-gramo-total-fr","22":"pa_bullet-point-3-fr-300-gramme-total-fr","23":"pa_bullet-point-3-it-300-grammo-total-fr","24":"pa_bullet-point-4-indulge-yourself-be-sure-not-to-run-out-of-stock-fr","25":"pa_bullet-point-4-de-dass-ihnen-nicht-der-vorrat-ausgeht-fr","26":"pa_bullet-point-4-de-stellen-sie-sicher-fr","27":"pa_bullet-point-4-esp-asegurese-de-no-quedarse-sin-existencias-fr","28":"pa_bullet-point-4-fr-veillez-a-ne-pas-etre-en-rupture-de-stock-fr","29":"pa_bullet-point-4-it-assicurati-di-non-esaurire-le-scorte-fr","30":"pa_bullet-point-5-order-belgian-sauce-now-fr","31":"pa_bullet-point-5-de-bestellen-sie-devos-lemmens-jetzt-fr","32":"pa_bullet-point-5-esp-comprar-mayonesa-de-vos-lemmens-ahora-fr","33":"pa_bullet-point-5-fr-acheter-sauce-cocktail-devos-maintenant-fr","34":"pa_bullet-point-5-it-compra-salsa-devos-lemmens-ora-fr","35":"pa_title-de-devos-lemmens-saucen-mayonnaise-mit-zitrone-300-ml-belgische-saucen-devos-lemmens-300-gramm-total-fr","36":"pa_title-esp-devos-lemmens-salsas-mayonesa-con-limon-300-ml-salsas-belgas-mayonesa-de-vos-lemmens-300-gramo-total-fr","37":"pa_title-fr-devos-lemmens-mayonnaise-au-citron-300-ml-sauce-devos-lemmens-sauce-cocktail-devos-300-gramme-total-fr","38":"pa_title-it-devos-lemmens-maionese-al-limone-300-ml-salsa-belgio-salsa-devos-lemmens-300-grammo-total-fr","40":"first","41":"instock","42":"sale","43":"taxable","44":"shipping-taxable","45":"purchasable","46":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/worldofeurope.com\/fr\/wp-json\/wp\/v2\/product\/127251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/worldofeurope.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/worldofeurope.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/worldofeurope.com\/fr\/wp-json\/wp\/v2\/media\/127252"}],"wp:attachment":[{"href":"https:\/\/worldofeurope.com\/fr\/wp-json\/wp\/v2\/media?parent=127251"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/worldofeurope.com\/fr\/wp-json\/wp\/v2\/product_brand?post=127251"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/worldofeurope.com\/fr\/wp-json\/wp\/v2\/product_cat?post=127251"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/worldofeurope.com\/fr\/wp-json\/wp\/v2\/product_tag?post=127251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}