{"id":123917,"date":"2022-03-11T09:12:59","date_gmt":"2022-03-11T09:12:59","guid":{"rendered":"https:\/\/worldofeurope.com\/shop\/sem%20categoria\/smint-breath-mints-smint-xl-tin-peppermint-pack-of-12-smint-breath-mints-sugar-free-mints-smint-mints\/"},"modified":"2025-11-17T22:05:33","modified_gmt":"2025-11-17T22:05:33","slug":"smint-breath-mints-smint-xl-tin-peppermint-pack-of-12-smint-breath-mints-sugar-free-mints-smint-mints","status":"publish","type":"product","link":"https:\/\/worldofeurope.com\/pt-pt\/shop\/doces\/smint-breath-mints-smint-xl-tin-peppermint-pack-of-12-smint-breath-mints-sugar-free-mints-smint-mints\/","title":{"rendered":"Pastilhas Smint para o h\u00e1lito | Smint XL Tin Peppermint | Embalagem de 12 pastilhas Smint | Pastilhas sem a\u00e7\u00facar | Pastilhas Smint"},"content":{"rendered":"<p>As pastilhas SMINT s\u00e3o doces totalmente sem a\u00e7\u00facar e ado\u00e7adas naturalmente. A melhor parte \u00e9 que n\u00e3o deixam um sabor desagrad\u00e1vel na boca. A pastilha de hortel\u00e3 SMINT \u00e9 a escolha ideal para aliviar a boca seca, promover um h\u00e1lito fresco e pode ajudar a prevenir c\u00e1ries. Basta levar esta lata consigo para onde quer que v\u00e1 e desfrutar de um refresco a qualquer hora do dia.<br \/>\nAs pastilhas SMINT ajudam a manter o h\u00e1lito fresco e hidratam a boca. S\u00e3o ideais para refrescar a boca e tamb\u00e9m s\u00e3o boas para os dentes. As nossas pastilhas sem a\u00e7\u00facar v\u00eam numa embalagem pr\u00e1tica e f\u00e1cil de transportar, para que possa manter-se fresco na estrada, no trabalho ou com os seus amigos. Estas pastilhas proporcionam um sabor fresco e refrescante, sendo uma boa alternativa a outros refrescantes bucais. Encomende agora as pastilhas para o h\u00e1lito Smint!<br \/>\nCom a hortel\u00e3-pimenta Smint, ter\u00e1 um refresco delicioso consigo a qualquer momento do dia. Estas pastilhas SMINT s\u00e3o extragrandes e t\u00eam sabor a hortel\u00e3-pimenta. Encomende agora!<br \/>\nN\u00e3o \u00e9 um sabor comum! As pastilhas de hortel\u00e3 SMINT combinam um sabor \u00fanico e mentolado que far\u00e1 de si um f\u00e3 para sempre!<\/p>\n<p><span style=\"font-weight: 400;\">Pastilhas SMINT sem a\u00e7\u00facar com o sabor fresco da menta <\/span><\/p>\n<p><span style=\"font-weight: 400;\"> Com estas pastilhas SMINT, nunca mais vai sair de casa sem um h\u00e1lito fresco <\/span><\/p>\n<p><span style=\"font-weight: 400;\"> Embalagem com 12 pastilhas Smint Breath <\/span><\/p>\n<p><span style=\"font-weight: 400;\"> Encomende agora estes SMINTs! <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As pastilhas SMINT s\u00e3o doces totalmente sem a\u00e7\u00facar e ado\u00e7ados naturalmente. A melhor parte \u00e9 que n\u00e3o deixam um sabor desagrad\u00e1vel na boca. SMINT \u00e9 a escolha certa para aliviar a boca seca, promover um h\u00e1lito fresco e pode ajudar a prevenir c\u00e1ries. Basta levar esta lata consigo para onde quer que v\u00e1 e desfrutar de um refresco a qualquer hora do dia.<br \/>\nAs pastilhas SMINT ajudam a manter o h\u00e1lito fresco e hidratam a boca. S\u00e3o ideais para refrescar a boca e tamb\u00e9m s\u00e3o boas para os dentes. As nossas pastilhas sem a\u00e7\u00facar v\u00eam numa embalagem pr\u00e1tica e f\u00e1cil de transportar, para que possa manter-se fresco na estrada, no trabalho ou com os seus amigos. Estas pastilhas Smint proporcionam um sabor fresco e refrescante, sendo uma boa alternativa a outros refrescantes bucais. Encomende agora os rebu\u00e7ados para o h\u00e1lito Smint!<br \/>\nCom Smint, tem um refresco delicioso consigo a qualquer hora do dia. Estes rebu\u00e7ados SMINT s\u00e3o extragrandes e t\u00eam sabor a hortel\u00e3-pimenta. Encomende agora!<\/p>\n","protected":false},"featured_media":123918,"template":"","meta":[],"product_brand":[],"product_cat":[79947,80109],"product_tag":[130615,130618,79870,130609],"class_list":{"0":"post-123917","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-doces","7":"product_cat-doces-2","8":"product_tag-au_ll","9":"product_tag-ca_ll","10":"product_tag-paises-baixos","11":"product_tag-uk_ll","12":"pa_bullet-point-1-not-your-ordinary-flavor-smint-mints-combine-a-unique-and-minty-flavor-that-will-make-you-a-forever-fan-pt-pt","13":"pa_bullet-point-1-de-smints-aus-holland-pt-pt","14":"pa_bullet-point-1-esp-smint-menta-de-holanda-pt-pt","15":"pa_bullet-point-1-fr-smint-menthe-de-la-hollande-pt-pt","16":"pa_bullet-point-1-it-smints-dallolanda-pt-pt","17":"pa_bullet-point-2-a-sugar-free-mints-with-the-fresh-of-mint-pt-pt","18":"pa_bullet-point-2-de-smint-clean-breath-zum-geniessen-mit-der-familie-oder-mit-freunden-pt-pt","19":"pa_bullet-point-2-esp-smints-para-disfrutar-con-la-familia-o-los-amigos-pt-pt","20":"pa_bullet-point-2-fr-smint-mints-a-savourer-en-famille-ou-entre-amis-pt-pt","21":"pa_bullet-point-2-it-smint-caramelle-per-godere-con-la-famiglia-o-gli-amici-pt-pt","22":"pa_bullet-point-3-with-these-smints-you-are-never-on-the-go-without-a-fresh-breath-pt-pt","23":"pa_bullet-point-3-de-pack-von-12-420-gram-total-pt-pt","24":"pa_bullet-point-3-esp-paquete-de-12-420-gram-total-pt-pt","25":"pa_bullet-point-3-fr-pack-de-12-420-gram-total-pt-pt","26":"pa_bullet-point-3-it-pacchetto-di-12-420-gram-total-pt-pt","27":"pa_bullet-point-4-pack-of-12-smint-breath-mints-pt-pt","28":"pa_bullet-point-4-de-dass-ihnen-nicht-der-vorrat-ausgeht-pt-pt","29":"pa_bullet-point-4-de-stellen-sie-sicher-pt-pt","30":"pa_bullet-point-4-esp-asegurese-de-no-quedarse-sin-existencias-pt-pt","31":"pa_bullet-point-4-fr-veillez-a-ne-pas-etre-en-rupture-de-stock-pt-pt","32":"pa_bullet-point-4-it-assicurati-di-non-esaurire-le-scorte-pt-pt","33":"pa_bullet-point-5-order-these-smints-now-pt-pt","34":"pa_bullet-point-5-de-bestellen-sie-smint-mint-jetzt-pt-pt","35":"pa_bullet-point-5-esp-comprar-smint-clean-breath-ahora-pt-pt","36":"pa_bullet-point-5-fr-acheter-smint-value-pack-maintenant-pt-pt","37":"pa_bullet-point-5-it-compra-smint-breath-mints-ora-pt-pt","38":"pa_title-de-smints-xl-dose-pfefferminz-smint-clean-breath-smint-mint-12-pack-420-gram-total-pt-pt","39":"pa_title-esp-smint-menta-lata-xl-menta-smints-smint-clean-breath-12-pack-420-gramo-total-pt-pt","40":"pa_title-it-smints-xl-tin-peppermint-smint-caramelle-smint-breath-mints-12-pack-420-grammi-total-pt-pt","42":"first","43":"instock","44":"sale","45":"taxable","46":"shipping-taxable","47":"purchasable","48":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/worldofeurope.com\/pt-pt\/wp-json\/wp\/v2\/product\/123917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/worldofeurope.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/worldofeurope.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/worldofeurope.com\/pt-pt\/wp-json\/wp\/v2\/media\/123918"}],"wp:attachment":[{"href":"https:\/\/worldofeurope.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=123917"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/worldofeurope.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=123917"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/worldofeurope.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=123917"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/worldofeurope.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=123917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}